{"id":115870,"date":"2020-04-11T13:01:59","date_gmt":"2020-04-11T13:01:59","guid":{"rendered":"https:\/\/www.mundiplus.com\/mosteiro-de-samos\/"},"modified":"2020-04-11T13:01:59","modified_gmt":"2020-04-11T13:01:59","slug":"mosteiro-de-samos","status":"publish","type":"post","link":"https:\/\/www.mundiplus.com\/pt-pt\/blog\/mosteiro-de-samos\/","title":{"rendered":"Mosteiro de Samos"},"content":{"rendered":"<p>O Mosteiro Beneditino de S\u00e3o Juli\u00e3o e Bas\u00edlisa (conhecido popularmente como Mosteiro de Samos) encontra-se no <a href=\"https:\/\/www.mundiplus.com\/pt-pt\/caminos\/a-pie\/camino-frances\" target=\"_blank\" rel=\"noopener noreferrer\">Caminho Franc\u00eas<\/a>, pr\u00f3ximo do m\u00edtico O Cebreiro, na prov\u00edncia de Lugo e encaixado num precioso vale, localizado na localidade de Samos.<\/p>\n<p>Na nossa humilde opini\u00e3o, o Mosteiro de Samos \u00e9 provavelmente, depois da Catedral de Santiago e junto \u00e0 Igreja de Santa Maria la Blanca em Villalc\u00e1zar de Sirga, um dos melhores e mais significativos templos religiosos do Caminho de Santiago Franc\u00eas.<\/p>\n<p>At\u00e9 que n\u00e3o se chega fisicamente aos p\u00e9s do mesmo, n\u00e3o se pode imaginar a grandeza do mesmo, devido ao local onde se encontra, aos p\u00e9s do rio Sarria ou Oribio e \u00e0 pequena localidade que o envolve.<\/p>\n<p>Est\u00e1 considerado como Monumento Nacional e Bem de Interesse Cultural. No seu interior alberga, entre outras divis\u00f5es, uma famosa Pousada de Peregrinos para aqueles que realizam o <a href=\"https:\/\/www.mundiplus.com\/pt-pt\/\" target=\"_blank\" rel=\"noopener\">Viagem organizada ao Caminho de Santiago<\/a>.<\/p>\n<p>\u00c9 o mosteiro habitado mais antigo de Espanha e um dos tr\u00eas que se encontram na Galiza com estas caracter\u00edsticas.<\/p>\n<p>A sua hist\u00f3ria remonta ao s\u00e9culo VI, segundo uma l\u00e1pide visig\u00f3tica que o atesta, fundado por S\u00e3o Martinho de Dumio, tendo sido posteriormente ampliado ao longo dos s\u00e9culos.<\/p>\n<p>Sofreu diversos contratempos, entre outros, pela invas\u00e3o mu\u00e7ulmana, pelo que foi temporariamente abandonado e tamb\u00e9m serviu de ref\u00fagio, na sua inf\u00e2ncia, para o que viria a ser Afonso II o Casto, Rei das Ast\u00farias, facto que foi decisivo para a expans\u00e3o econ\u00f3mica, art\u00edstica e cultural do referido Mosteiro e, por conseguinte, do Caminho de Santiago, pois foi durante o reinado do rei Afonso II que foi descoberta a <a href=\"https:\/\/www.mundiplus.com\/pt-pt\/blog\/la-tumba-del-apostol-santiago-y-sus-origenes\" target=\"_blank\" rel=\"noopener noreferrer\">tumba do Ap\u00f3stolo Santiago<\/a>.<\/p>\n<p><img fetchpriority=\"high\" decoding=\"async\" class=\"aligncenter wp-image-14050 size-large\" src=\"https:\/\/www.mundiplus.com\/wp-content\/uploads\/2024\/04\/Claustro-monasterio-de-samos-1-1024x683.jpg\" alt=\"Claustro-monasterio-de-samos\" width=\"1024\" height=\"683\" \/><\/p>\n<p>Depois de algumas vicissitudes, no que diz respeito \u00e0s Ordens mon\u00e1sticas que o habitaram, foi no s\u00e9culo XII, com a Reforma da Ordem de Cluny, que o Mosteiro alcan\u00e7ou grande import\u00e2ncia.<\/p>\n<p>Tal como no resto de Espanha, sofreu a &#8220;Desamortiza\u00e7\u00e3o de Mendiz\u00e1bal&#8221; em 1836, pelo que a comunidade beneditina que ali residia teve que abandonar o mosteiro, at\u00e9 1880, ano em que p\u00f4de regressar.<\/p>\n<p>Desde o s\u00e9culo X, a Ordem Beneditina, titular do Mosteiro, rege-se pela Regra de S\u00e3o Bento.<\/p>\n<p>A constru\u00e7\u00e3o do <a href=\"https:\/\/www.abadiadesamos.com\/\" target=\"_blank\" rel=\"nofollow noopener\">Mosteiro de Samos<\/a> desenvolve-se, principalmente, entre os s\u00e9culos XVI e XVIII (estilo renascentista e barroco).<\/p>\n<p>Destacamos a Igreja, edif\u00edcio neocl\u00e1ssico de planta retangular, com tr\u00eas naves, assim como o seu altar-mor e a escadaria, muito semelhante \u00e0 da Catedral de Santiago na sua entrada pela Pra\u00e7a do Obradoiro, bem como a sua sacristia e a fabulosa biblioteca que cont\u00e9m alguns &#8220;incun\u00e1bulos&#8221; e cole\u00e7\u00f5es como &#8220;A Patologia Grega&#8221; e &#8220;Latina&#8221;, assim como &#8220;Sacrorum Conciliorum nova et amplissima&#8221;.<\/p>\n<p><img decoding=\"async\" class=\"aligncenter wp-image-14046 size-full\" src=\"https:\/\/www.mundiplus.com\/wp-content\/uploads\/2024\/04\/UNADJUSTEDNONRAW_thumb_1223.jpg\" alt=\"monasterio-de-samos-capilla-cipres\" width=\"1024\" height=\"768\" \/><\/p>\n<p>O mosteiro conta com dois claustros: &#8220;O claustro mais grande de Espanha ou do Padre Feijoo&#8221;, do s\u00e9culo XVIII, onde se encontra a est\u00e1tua do monge beneditino, que tomou os h\u00e1bitos neste Mosteiro, e &#8220;O Claustro das Nereidas&#8221;, do s\u00e9culo XVI.<\/p>\n<p>\u00c9 tamb\u00e9m de destacar, nas proximidades do Mosteiro, a Capela do Cipreste, obra do s\u00e9culo IX, de estilo mo\u00e7\u00e1rabe (com portas de arco de ferradura), que poder\u00e1 ter tido fun\u00e7\u00f5es de albergue de peregrinos ou cela mon\u00e1stica.<\/p>\n<p>Junto a esta capela, encontra-se um impressionante cipreste, que d\u00e1 nome a esta capela, com uma antiguidade aproximada de mil anos.<\/p>\n<p>Como conclus\u00e3o, poder\u00edamos dizer que o Mosteiro de Samos bem vale uma paragem no nosso <a href=\"https:\/\/www.mundiplus.com\/pt-pt\/caminos\/a-pie\/camino-frances\/o-cebreiro-santiago\" target=\"_blank\" rel=\"noopener noreferrer\">Caminho de Santiago desde O Cebreiro<\/a>, antes de chegar \u00e0 localidade de Sarria. Para visit\u00e1-lo em profundidade, dever\u00e1 pernoitar em Samos para que tenha tempo suficiente para visitar com calma o seu interior com a ajuda dos monges beneditinos, que ser\u00e3o guias excecionais daquilo que \u00e9 &#8220;a sua casa&#8221;. Outra op\u00e7\u00e3o, caso queira visit\u00e1-lo e n\u00e3o tenha 9 dias para iniciar a rota desde o alto de O Cebreiro, \u00e9 contratar o <a href=\"https:\/\/www.mundiplus.com\/pt-pt\/caminos\/a-pie\/camino-frances\/camino-de-santiago-desde-sarria\" target=\"_blank\" rel=\"noopener\">Caminho de Santiago organizado desde Sarria<\/a>. Neste caso, s\u00f3 precisar\u00e1 de 7 dias de viagem, e ter\u00e1 que passar uma noite adicional em Sarria, e a partir da\u00ed podemos lev\u00e1-lo numa viagem de ida e volta para visitar a Abadia de Samos.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>O Mosteiro Beneditino de S\u00e3o Juli\u00e3o e Bas\u00edlisa (conhecido popularmente como Mosteiro de Samos) encontra-se no Caminho Franc\u00eas, pr\u00f3ximo do m\u00edtico O Cebreiro, na prov\u00edncia de Lugo e encaixado num precioso vale, localizado na localidade de Samos. Na nossa humilde opini\u00e3o, o Mosteiro de Samos \u00e9 provavelmente, depois da Catedral de Santiago e junto \u00e0 [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":115871,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[574,578],"tags":[],"class_list":["post-115870","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-blog-do-caminho","category-caminho-a-pe"],"_links":{"self":[{"href":"https:\/\/www.mundiplus.com\/pt-pt\/wp-json\/wp\/v2\/posts\/115870","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.mundiplus.com\/pt-pt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.mundiplus.com\/pt-pt\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.mundiplus.com\/pt-pt\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.mundiplus.com\/pt-pt\/wp-json\/wp\/v2\/comments?post=115870"}],"version-history":[{"count":0,"href":"https:\/\/www.mundiplus.com\/pt-pt\/wp-json\/wp\/v2\/posts\/115870\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.mundiplus.com\/pt-pt\/wp-json\/wp\/v2\/media\/115871"}],"wp:attachment":[{"href":"https:\/\/www.mundiplus.com\/pt-pt\/wp-json\/wp\/v2\/media?parent=115870"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.mundiplus.com\/pt-pt\/wp-json\/wp\/v2\/categories?post=115870"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.mundiplus.com\/pt-pt\/wp-json\/wp\/v2\/tags?post=115870"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}