{"id":111755,"date":"2023-10-23T21:41:18","date_gmt":"2023-10-23T21:41:18","guid":{"rendered":"https:\/\/www.mundiplus.com\/caminos\/sem categoria\/ruta-del-padre-sarmiento\/"},"modified":"2023-10-23T21:41:18","modified_gmt":"2023-10-23T21:41:18","slug":"ruta-del-padre-sarmiento","status":"publish","type":"product","link":"https:\/\/www.mundiplus.com\/pt-pt\/caminos\/ruta-del-padre-sarmiento\/","title":{"rendered":"Ruta del Padre Sarmiento"},"content":{"rendered":"<p>Embora tecnicamente n\u00e3o possa ser considerado &#8220;especificamente&#8221; como parte de qualquer Caminho Portugu\u00eas, devido \u00e0 sua singularidade, beleza e percurso que passa por algumas das etapas e regi\u00f5es que coincidem com esta rota, inclu\u00edmo-la nesta<br \/> Classifica\u00e7\u00e3o.<\/p>\n<p>A rota percorre os munic\u00edpios de Poio, Sanxenxo, O Grove, Mea\u00f1o, Cambados, Vilanova de Arousa, A Illa de Arousa e Vilagarc\u00eda. Mas esta maravilhosa rota oferece muito mais do que hist\u00f3ria e paisagens.<\/p>\n<p>Ao longo de 190 quil\u00f4metros, respira-se n\u00e3o apenas o ar mar\u00edtimo, mas tamb\u00e9m toda a hist\u00f3ria e tradi\u00e7\u00f5es da regi\u00e3o, refletida na sua arquitetura civil e religiosa, em solares como os de Cambados, Rubianes, Ulloa, Torrado e Vista Real, s\u00edtios arqueol\u00f3gicos ou pitorescas vilas de pescadores e praias para todos os gostos.<\/p>\n<p>E n\u00e3o importa em qual esta\u00e7\u00e3o do ano se decida iniciar esta rota maravilhosa e \u00fanica; o clima oce\u00e2nico da regi\u00e3o \u00e9 suave e \u00famido, com invernos de m\u00ednimas de 10 graus e ver\u00f5es onde as m\u00e1ximas n\u00e3o ultrapassam os 30 graus em julho e agosto.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Embora tecnicamente n\u00e3o possa ser considerado &#8220;especificamente&#8221; como parte de qualquer Caminho Portugu\u00eas, devido \u00e0 sua singularidade, beleza e percurso que passa por algumas das etapas e regi\u00f5es que coincidem com esta rota, inclu\u00edmo-la nesta Classifica\u00e7\u00e3o. A rota percorre os munic\u00edpios de Poio, Sanxenxo, O Grove, Mea\u00f1o, Cambados, Vilanova de Arousa, A Illa de Arousa [&hellip;]<\/p>\n","protected":false},"featured_media":109837,"comment_status":"open","ping_status":"closed","template":"","meta":{"_joinchat":[]},"product_brand":[],"product_cat":[560,556],"product_tag":[],"class_list":["post-111755","product","type-product","status-publish","has-post-thumbnail","product_cat-camino-portugues-pt-pt","product_cat-caminos-a-pie","first","instock","shipping-taxable","purchasable","product-type-simple"],"_links":{"self":[{"href":"https:\/\/www.mundiplus.com\/pt-pt\/wp-json\/wp\/v2\/product\/111755","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.mundiplus.com\/pt-pt\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.mundiplus.com\/pt-pt\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/www.mundiplus.com\/pt-pt\/wp-json\/wp\/v2\/comments?post=111755"}],"version-history":[{"count":0,"href":"https:\/\/www.mundiplus.com\/pt-pt\/wp-json\/wp\/v2\/product\/111755\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.mundiplus.com\/pt-pt\/wp-json\/wp\/v2\/media\/109837"}],"wp:attachment":[{"href":"https:\/\/www.mundiplus.com\/pt-pt\/wp-json\/wp\/v2\/media?parent=111755"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/www.mundiplus.com\/pt-pt\/wp-json\/wp\/v2\/product_brand?post=111755"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.mundiplus.com\/pt-pt\/wp-json\/wp\/v2\/product_cat?post=111755"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.mundiplus.com\/pt-pt\/wp-json\/wp\/v2\/product_tag?post=111755"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}